{"id":129449,"date":"2025-10-31T17:10:00","date_gmt":"2025-10-31T16:10:00","guid":{"rendered":"https:\/\/ibecbarcelona.eu\/?p=129449"},"modified":"2025-10-31T15:44:27","modified_gmt":"2025-10-31T14:44:27","slug":"primer-trasplante-en-cerdos-de-rinones-porcinos-modificados-con-organoides-renales-humanos","status":"publish","type":"post","link":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplante-en-cerdos-de-rinones-porcinos-modificados-con-organoides-renales-humanos\/","title":{"rendered":"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos"},"content":{"rendered":"\n<p><strong>Un equipo de investigaci\u00f3n ha desarrollado una tecnolog\u00eda pionera que permite producir organoides renales humanos de manera escalable, combinarlos con ri\u00f1ones de cerdo fuera del cuerpo y trasplantarlos de nuevo al mismo animal de manera viable.<\/strong> <strong>El experimento, liderado por el Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), se encuentra en fase precl\u00ednica y confirma la seguridad y viabilidad del procedimiento, abriendo la puerta a futuros ensayos en contextos m\u00e1s cercanos al humano. <\/strong> <strong>A largo plazo, esta aproximaci\u00f3n podr\u00eda contribuir a alargar la vida \u00fatil de los \u00f3rganos destinados al trasplante y ofrecer una alternativa terap\u00e9utica para enfermos renales cr\u00f3nicos.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-1024x683.jpg\" alt=\"\" class=\"wp-image-129494 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-1024x683.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-300x200.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-768x512.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-1536x1024.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-2048x1365.jpg 2048w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-1200x800.jpg 1200w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-600x400.jpg 600w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/683;\" \/><figcaption class=\"wp-element-caption\">Elena Garreta Bahima (izquierda) y Daniel Moya Rull (derecha) en los laboratorios del IBEC.<\/figcaption><\/figure>\n\n\n\n<p>Un equipo de investigaci\u00f3n liderado por el Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), en colaboraci\u00f3n con el Instituto de Investigaci\u00f3n Biom\u00e9dica de A Coru\u00f1a (INIBIC) y grupos de investigaci\u00f3n internacionales, ha desarrollado una tecnolog\u00eda pionera que permite producir organoides renales humanos de manera escalable, combinarlos con ri\u00f1ones de cerdo fuera del cuerpo y trasplantarlos de nuevo al mismo animal,&nbsp; evaluando su viabilidad despu\u00e9s del trasplante. El estudio, publicado en la revista <em>Nature Biomedical Engineering<\/em>, representa un hito en el campo de la medicina regenerativa y personalizada, estableciendo las bases para la utilizaci\u00f3n de organoides de ri\u00f1\u00f3n derivados de c\u00e9lulas madre humanas para terapia celular en ensayos cl\u00ednicos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>El objetivo a largo plazo es poder regenerar o reparar un \u00f3rgano antes del trasplante. Esto podr\u00eda reducir el tiempo de espera de los pacientes cr\u00f3nicos y aumentar el n\u00famero de \u00f3rganos viables para el trasplante<\/em>.<\/p>\n\n\n\n<p>N\u00faria Montserrat<\/p>\n<\/blockquote>\n\n\n\n<p>Este trabajo, liderado por la <strong>Dra. N\u00faria Montserrat<\/strong>, investigadora ICREA en el IBEC en el momento del estudio y actual consejera del Departamento de Investigaci\u00f3n y Universidades de la Generalidad de Catalu\u00f1a, es el resultado de una trayectoria cient\u00edfica de m\u00e1s de una d\u00e9cada dedicada a la medicina regenerativa y a la bioingenier\u00eda de \u00f3rganos. Fruto de esta l\u00ednea de investigaci\u00f3n sostenida, el equipo de investigaci\u00f3n ha conseguido combinar por primera vez organoides renales humanos con ri\u00f1ones porcinos vivos, conectados a m\u00e1quinas de perfusi\u00f3n normot\u00e9rmica. El uso de estos dispositivos, utilizados habitualmente en el quir\u00f3fano para mantener el \u00f3rgano vivo y oxigenado fuera del cuerpo antes de un transplante, ha permitido insertar organoides humanos dentro de los ri\u00f1ones porcinos y monitorear en tiempo real su integraci\u00f3n y funci\u00f3n.<\/p>\n\n\n\n<p>\u00ab<em>Nuestra investigaci\u00f3n demuestra que la combinaci\u00f3n de tecnolog\u00edas de organoides y perfusi\u00f3n ex vivo puede permitir intervenciones celulares en condiciones totalmente controladas<\/em>.\u00bb explica la Dra. Montserrat. \u00ab<em>El objetivo a largo plazo es poder regenerar o reparar un \u00f3rgano antes del trasplante. Esto podr\u00eda reducir el tiempo de espera de los pacientes cr\u00f3nicos y aumentar el n\u00famero de \u00f3rganos viables para el trasplante<\/em>.\u00bb<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Una tecnolog\u00eda escalable y segura<\/strong><strong><\/strong><\/h4>\n\n\n\n<p>Un organoide de ri\u00f1\u00f3n es una estructura tridimensional, de unas micras de tama\u00f1o, cultivada en el laboratorio a partir de c\u00e9lulas madre humanas. Aunque no es un \u00f3rgano completo, reproduce muchas de sus estructuras y funciones principales. Gracias a estas caracter\u00edsticas, los organoides permiten estudiar c\u00f3mo se desarrolla el ri\u00f1\u00f3n, probar nuevos f\u00e1rmacos y, en el futuro, se espera que puedan ser utilizados para reparar tejidos renales da\u00f1ados o mejorar \u00f3rganos destinados al trasplante.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><em>Ahora, con nuestro nuevo m\u00e9todo, podemos generar miles de organoides renales en condiciones controladas y en poco tiempo, con una gran precisi\u00f3n y sin necesidad de componentes complejos.<\/em><\/p>\n\n\n\n<p>Elena Garreta<\/p>\n<\/blockquote>\n\n\n\n<p>El estudio describe, por primera vez, un m\u00e9todo sistem\u00e1tico y escalable para producir miles de estos organoides renales humanos, utilizando t\u00e9cnicas de microagregaci\u00f3n e ingenier\u00eda gen\u00e9tica.<\/p>\n\n\n\n<p>\u00ab<em>A pesar del gran potencial cl\u00ednico de los organoides, hasta ahora uno de los grandes retos para aplicar esta tecnolog\u00eda en tratamientos m\u00e9dicos reales era conseguir producir estos organoides de manera escalable, uniforme y asequible. Ahora, con nuestro nuevo m\u00e9todo, podemos generar miles de organoides renales en condiciones controladas y en poco tiempo, con una gran precisi\u00f3n y sin necesidad de componentes complejos. Esto abre la puerta a aplicaciones como la detecci\u00f3n de f\u00e1rmacos o el estudio de enfermedades.<\/em>\u00ab, a\u00f1ade la Dra. Elena Garreta, investigadora senior del grupo de <a href=\"https:\/\/ibecbarcelona.eu\/research-groups\/pluripotency-for-organ-regeneration\/\">Puripotencia para la regeneraci\u00f3n de \u00f3rganos<\/a> del IBEC y co-primera autora del estudio.<\/p>\n\n\n\n<p>Por otro lado, la utilizaci\u00f3n de las m\u00e1quinas mencionadas, para llevar a cabo la perfusi\u00f3n de los organoides dentro de los ri\u00f1ones, ofrece una ventaja clave: permite medir par\u00e1metros fisiol\u00f3gicos del \u00f3rgano en tiempo real y detectar de manera inmediata cualquier signo de da\u00f1o o rechazo. Los experimentos se realizaron tanto <em>ex vivo<\/em> (fuera del organismo) como <em>in vivo<\/em> (en el mismo animal), utilizando un modelo porcino de trasplante muy similar al ri\u00f1\u00f3n humano.<\/p>\n\n\n\n<p>El equipo de investigaci\u00f3n observ\u00f3 que, despu\u00e9s de 24 y 48 horas del trasplante, los organoides humanos persist\u00edan integrados en el tejido renal porcino, manten\u00edan su viabilidad y no desencadenaban ninguna respuesta inmune significativa. El ri\u00f1\u00f3n trasplantado continuaba funcionando con normalidad, y no se detectaron signos de da\u00f1o ni toxicidad.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Hacia la regeneraci\u00f3n de \u00f3rganos antes del trasplante<\/strong><strong><\/strong><\/h4>\n\n\n\n<p>Seg\u00fan los autores y las autoras, esta metodolog\u00eda permite imaginar un escenario cl\u00ednico en el que los \u00f3rganos destinados al trasplante puedan ser tratados y acondicionados antes de implantarlos. En este contexto, la colaboraci\u00f3n con el Instituto de Investigaci\u00f3n Biom\u00e9dica de A Coru\u00f1a (INIBIC), la Organizaci\u00f3n Nacional de Trasplantes (ONT) y otras instituciones, como el Instituto de Salud Carlos III (ISCIII), ha sido esencial para trasladar la investigaci\u00f3n a un entorno quir\u00fargico realista y precl\u00ednico.<\/p>\n\n\n\n<figure class=\"wp-block-video\"><video autoplay controls loop muted src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/NMontserrat-Organoides_20251.mp4\"><\/video><figcaption class=\"wp-element-caption\">Im\u00e1genes tridimensionales (Z-stack) de organoides de ri\u00f1\u00f3n en el d\u00eda 16 de diferenciaci\u00f3n obtenidas por microscop\u00eda confocal. Las c\u00e9lulas han sido marcadas con diferentes colores mediante la t\u00e9cnica de inmunofluorescencia para identificar componentes espec\u00edficos: MEIS (verde: c\u00e9lulas del espacio intersticial), CD31 (rojo: c\u00e9lulas endoteliales), LTL (magenta: t\u00fabulos renales) y DAPI (azul: n\u00facleos celulares). Esta imagen permite observar c\u00f3mo se organizan los diferentes tipos de c\u00e9lulas dentro del organoide renal. Organoide generado a partir de la agregaci\u00f3n de 250,000 c\u00e9lulas progenitoras renales obtenidas de c\u00e9lulas madre pluripotentes humanas siguiendo un proceso de diferenciaci\u00f3n.<\/figcaption><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>Un trabajo colaborativo y de gran impacto<\/strong><strong><\/strong><\/h4>\n\n\n\n<p>El art\u00edculo, titulado \u00abSystematic production of human kidney organoids for transplantation in porcine kidneys during <em>ex vivo <\/em>machine perfusion\u00bb, ha sido fruto de la colaboraci\u00f3n entre el IBEC, el INIBIC, el CIBER-BBN, la ONT, la UB, el Instituto de Investigaci\u00f3n Sanitaria de Navarra, el Instituto de Investigaci\u00f3n Biom\u00e9dica de M\u00e1laga, la Universidad de California, el Center for Bioengineering and Tissue Regeneration de California,\u00a0 el Instituto de Investigaci\u00f3n en Ciencias de la Alimentaci\u00f3n (CSIC-UAM), el University Medical Center Groningen, University Hospitals Leuven, el National Center of Microbiology (ISCIII), el Instituto de investigaci\u00f3n Sanitaria HM Hospitales, la University of Leuven, el CIBERONC y el Networking Biomedical Research Center in Bioengineering. El trabajo tambi\u00e9n ha contado con la participaci\u00f3n de EBERS Medical Technology SL, la empresa desarrolladora de las m\u00e1quinas de perfusi\u00f3n utilizadas.<\/p>\n\n\n\n<p>La Dra. Elena Garreta es tambi\u00e9n profesora asociada en el Departamento de Biolog\u00eda Celular, Fisiolog\u00eda e Inmunolog\u00eda de la Universidad de Barcelona (UB) y coordinadora de la Plataforma ISCIII Biomodelos y Biobancos (PISCIIIBB) del Instituto de Salud Carlos III.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><strong>Art\u00edculo Original<\/strong><strong><\/strong><\/p>\n\n\n\n<p>Elena Garreta, Daniel Moya-Rull, Alberto Centeno, Andr\u00e9s Marco, Asier Ullate-Agote, Gaia Amato, Carlos J. Aranda, Roger Oria, Daniel Lozano-Ojalvo, Merel B. F. Pool, Tim L. Hamelink, Idoia Luc\u00eda Selfa, Federico Gonz\u00e1lez, Carolina Tarantino, Alejandro Montero Salinas, Patricia L\u00f3pez San Mart\u00edn, Priyanka Koshy, Aleix Gavald\u00e0-Navarro, Amaia Vilas-Zornoza, Juan R. Rodr\u00edguez-Madoz, Ant\u00f3n Fern\u00e1ndez Garc\u00eda, Inmaculada Marquez-Leiva, Henri G. D. Leuvenink,\u00a0 Cristobal Belda-Iniesta, Maarten Naesens, Beatriz Dominguez-Gil, Marcelino Gonz\u00e1lez-Mart\u00edn, Javier Rodr\u00edguez-Rivera, Jordi Ochando, Felipe Prosper, Cyril Moers &amp; Nuria Montserrat. <strong>Systematic production of human kidney organoids for transplantation in porcine kidneys during ex vivo machine perfusion. <\/strong><em>Nature Biomedical Engineering <\/em>(2025). DOI: <a href=\"https:\/\/www.nature.com\/articles\/s41551-025-01542-1\">10.1038\/s41551-025-01542-1<\/a><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n","protected":false},"excerpt":{"rendered":"<p>Un equipo de investigaci\u00f3n ha desarrollado una tecnolog\u00eda pionera que permite producir organoides renales humanos de manera escalable, combinarlos con ri\u00f1ones de cerdo fuera del cuerpo y trasplantarlos de nuevo al mismo animal de manera viable. El experimento, liderado por el Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), se encuentra en fase precl\u00ednica y confirma la seguridad y viabilidad del procedimiento, abriendo la puerta a futuros ensayos en contextos m\u00e1s cercanos al humano.  A largo plazo, esta aproximaci\u00f3n podr\u00eda contribuir a alargar la vida \u00fatil de los \u00f3rganos destinados al trasplante y ofrecer una alternativa terap\u00e9utica para enfermos renales cr\u00f3nicos.<\/p>\n","protected":false},"author":24,"featured_media":129494,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[97],"tags":[1124,1781],"post_formats":[],"class_list":["post-129449","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-de-investigacion","tag-nuria-montserrat-es-2","tag-pluripotency-for-organ-regeneration-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos - Institute for Bioengineering of Catalonia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos - Institute for Bioengineering of Catalonia\" \/>\n<meta property=\"og:description\" content=\"Un equipo de investigaci\u00f3n ha desarrollado una tecnolog\u00eda pionera que permite producir organoides renales humanos de manera escalable, combinarlos con ri\u00f1ones de cerdo fuera del cuerpo y trasplantarlos de nuevo al mismo animal de manera viable. El experimento, liderado por el Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), se encuentra en fase precl\u00ednica y confirma la seguridad y viabilidad del procedimiento, abriendo la puerta a futuros ensayos en contextos m\u00e1s cercanos al humano. A largo plazo, esta aproximaci\u00f3n podr\u00eda contribuir a alargar la vida \u00fatil de los \u00f3rganos destinados al trasplante y ofrecer una alternativa terap\u00e9utica para enfermos renales cr\u00f3nicos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/\" \/>\n<meta property=\"og:site_name\" content=\"Institute for Bioengineering of Catalonia\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-31T16:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bia Moreno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bia Moreno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/\"},\"author\":{\"name\":\"Bia Moreno\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/person\\\/b553413d524d76a399e659509449f8ec\"},\"headline\":\"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos\",\"datePublished\":\"2025-10-31T16:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/\"},\"wordCount\":1429,\"publisher\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EGarretaDMoya-scaled.jpg\",\"keywords\":[\"Nuria Montserrat\",\"Pluripotency for organ regeneration\"],\"articleSection\":[\"Noticias de investigaci\u00f3n\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/\",\"name\":\"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos - Institute for Bioengineering of Catalonia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EGarretaDMoya-scaled.jpg\",\"datePublished\":\"2025-10-31T16:10:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EGarretaDMoya-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/EGarretaDMoya-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#website\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/\",\"name\":\"Institute for Bioengineering of Catalonia\",\"description\":\"Bioengineering solutions for health\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibecbarcelona.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\",\"name\":\"Institute for Bioengineering of Catalonia\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-IBEC_20ANYS_GRIS.png\",\"contentUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-IBEC_20ANYS_GRIS.png\",\"width\":696,\"height\":257,\"caption\":\"Institute for Bioengineering of Catalonia\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/person\\\/b553413d524d76a399e659509449f8ec\",\"name\":\"Bia Moreno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g\",\"caption\":\"Bia Moreno\"},\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/author\\\/bmoreno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos - Institute for Bioengineering of Catalonia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/","og_locale":"es_ES","og_type":"article","og_title":"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos - Institute for Bioengineering of Catalonia","og_description":"Un equipo de investigaci\u00f3n ha desarrollado una tecnolog\u00eda pionera que permite producir organoides renales humanos de manera escalable, combinarlos con ri\u00f1ones de cerdo fuera del cuerpo y trasplantarlos de nuevo al mismo animal de manera viable. El experimento, liderado por el Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), se encuentra en fase precl\u00ednica y confirma la seguridad y viabilidad del procedimiento, abriendo la puerta a futuros ensayos en contextos m\u00e1s cercanos al humano. A largo plazo, esta aproximaci\u00f3n podr\u00eda contribuir a alargar la vida \u00fatil de los \u00f3rganos destinados al trasplante y ofrecer una alternativa terap\u00e9utica para enfermos renales cr\u00f3nicos.","og_url":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/","og_site_name":"Institute for Bioengineering of Catalonia","article_published_time":"2025-10-31T16:10:00+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg","type":"image\/jpeg"}],"author":"Bia Moreno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bia Moreno","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#article","isPartOf":{"@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/"},"author":{"name":"Bia Moreno","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/person\/b553413d524d76a399e659509449f8ec"},"headline":"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos","datePublished":"2025-10-31T16:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/"},"wordCount":1429,"publisher":{"@id":"https:\/\/ibecbarcelona.eu\/#organization"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#primaryimage"},"thumbnailUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg","keywords":["Nuria Montserrat","Pluripotency for organ regeneration"],"articleSection":["Noticias de investigaci\u00f3n"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/","url":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/","name":"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos - Institute for Bioengineering of Catalonia","isPartOf":{"@id":"https:\/\/ibecbarcelona.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#primaryimage"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#primaryimage"},"thumbnailUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg","datePublished":"2025-10-31T16:10:00+00:00","breadcrumb":{"@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#primaryimage","url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg","contentUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/ibecbarcelona.eu\/es\/primer-trasplantament-en-porcs-de-ronyons-porcins-modificats-amb-organoides-renals-humans\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibecbarcelona.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Primer trasplante en cerdos de ri\u00f1ones porcinos modificados con organoides renales humanos"}]},{"@type":"WebSite","@id":"https:\/\/ibecbarcelona.eu\/#website","url":"https:\/\/ibecbarcelona.eu\/","name":"Institute for Bioengineering of Catalonia","description":"Bioengineering solutions for health","publisher":{"@id":"https:\/\/ibecbarcelona.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibecbarcelona.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ibecbarcelona.eu\/#organization","name":"Institute for Bioengineering of Catalonia","url":"https:\/\/ibecbarcelona.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/logo\/image\/","url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/01\/cropped-IBEC_20ANYS_GRIS.png","contentUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/01\/cropped-IBEC_20ANYS_GRIS.png","width":696,"height":257,"caption":"Institute for Bioengineering of Catalonia"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/person\/b553413d524d76a399e659509449f8ec","name":"Bia Moreno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g","caption":"Bia Moreno"},"url":"https:\/\/ibecbarcelona.eu\/es\/author\/bmoreno\/"}]}},"AFP_featured_media_urls":{"full":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg",2560,1707,false],"thumbnail":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-150x150.jpg",150,150,true],"medium":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-300x200.jpg",300,200,true],"medium_large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-768x512.jpg",768,512,true],"large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-1024x683.jpg",1024,683,true]},"AFP_attachments":{"full":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-scaled.jpg",2560,1707,false],"thumbnail":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-150x150.jpg",150,150,true],"medium":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-300x200.jpg",300,200,true],"medium_large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-768x512.jpg",768,512,true],"large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/EGarretaDMoya-1024x683.jpg",1024,683,true]},"AFP_videos":{"129505":{"ID":129505,"post_author":"37","post_date":"2025-10-31 15:27:53","post_date_gmt":"2025-10-31 14:27:53","post_content":"","post_title":"NMontserrat-Organoides_2025(1)","post_excerpt":"","post_status":"inherit","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"nmontserrat-organoides_20251-2","to_ping":"","pinged":"","post_modified":"2025-10-31 15:27:53","post_modified_gmt":"2025-10-31 14:27:53","post_content_filtered":"","post_parent":129449,"guid":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/NMontserrat-Organoides_20251.mp4","menu_order":0,"post_type":"attachment","post_mime_type":"video\/mp4","comment_count":"0","filter":"raw"},"129506":129505},"AFP_video_blocks":"<figure class=\"wp-block-video\"><video autoplay controls loop muted src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2025\/10\/NMontserrat-Organoides_20251.mp4\"><\/video><figcaption class=\"wp-element-caption\">Im\u00e1genes tridimensionales (Z-stack) de organoides de ri\u00f1\u00f3n en el d\u00eda 16 de diferenciaci\u00f3n obtenidas por microscop\u00eda confocal. Las c\u00e9lulas han sido marcadas con diferentes colores mediante la t\u00e9cnica de inmunofluorescencia para identificar componentes espec\u00edficos: MEIS (verde: c\u00e9lulas del espacio intersticial), CD31 (rojo: c\u00e9lulas endoteliales), LTL (magenta: t\u00fabulos renales) y DAPI (azul: n\u00facleos celulares). Esta imagen permite observar c\u00f3mo se organizan los diferentes tipos de c\u00e9lulas dentro del organoide renal. Organoide generado a partir de la agregaci\u00f3n de 250,000 c\u00e9lulas progenitoras renales obtenidas de c\u00e9lulas madre pluripotentes humanas siguiendo un proceso de diferenciaci\u00f3n.<\/figcaption><\/figure>\n","AFP_category_names":["Noticias de investigaci\u00f3n"],"_links":{"self":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts\/129449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/comments?post=129449"}],"version-history":[{"count":5,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts\/129449\/revisions"}],"predecessor-version":[{"id":129520,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts\/129449\/revisions\/129520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/media\/129494"}],"wp:attachment":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/media?parent=129449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/categories?post=129449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tags?post=129449"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/post_formats?post=129449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}