
{"id":132465,"date":"2026-03-05T13:17:16","date_gmt":"2026-03-05T12:17:16","guid":{"rendered":"https:\/\/ibecbarcelona.eu\/?p=132465"},"modified":"2026-03-09T13:39:55","modified_gmt":"2026-03-09T12:39:55","slug":"nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day","status":"publish","type":"post","link":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/","title":{"rendered":"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day"},"content":{"rendered":"\n<p><strong>Expertos en nanomedicina se han reunido hoy, 05 de marzo, para debatir los \u00faltimos avances en el estudio, diagn\u00f3stico y tratamiento de las enfermedades raras. La jornada Nano Rare Diseases Day se ha organizado un a\u00f1o m\u00e1s con motivo del D\u00eda Mundial de las Enfermedades Raras, celebrado el 28 de febrero, y ha sido impulsada por el Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), como coordinador de NANOMED Spain, el Hospital Sant Joan de D\u00e9u y el Instituto de Investigaci\u00f3n Sant Joan de Deu.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"644\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-1024x644.jpg\" alt=\"\" class=\"wp-image-132427 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-1024x644.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-300x189.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-768x483.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-1536x966.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-2048x1289.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/644;\" \/><figcaption class=\"wp-element-caption\"><strong>Manuel Salmer\u00f3n<\/strong>, director del Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC).<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Las enfermedades raras son patolog\u00edas generalmente cr\u00f3nicas, degenerativas y que aparecen a menudo en la infancia. En Europa, una enfermedad se considera rara cuando afecta a menos de cinco personas por cada 10.000 habitantes. Se estima que existen entre 5.000 y 7.000 enfermedades de este tipo, y cerca de 4.000 todav\u00eda no cuentan con tratamientos efectivos. En conjunto, m\u00e1s de 300 millones de personas en el mundo viven con alguna de estas patolog\u00edas.<\/p>\n\n\n\n<p>Esta s\u00e9ptima edici\u00f3n del Nano Rare Diseases Day ha recibido a m\u00e1s de 70 asistentes, entre investigadores, profesionales cl\u00ednicos, representantes del sector industrial y pacientes. El encuentro ha ofrecido un espacio de intercambio para abordar los principales retos asociados a estas enfermedades y debatir posibles soluciones. Las intervenciones se han centrado especialmente en el papel de la nanomedicina en este \u00e1mbito, destacando su potencial para mejorar el diagn\u00f3stico temprano y contribuir al desarrollo de nuevas terapias.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"947\" height=\"722\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Joan-Comella.jpg\" alt=\"\" class=\"wp-image-132430 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Joan-Comella.jpg 947w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Joan-Comella-300x229.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Joan-Comella-768x586.jpg 768w\" data-sizes=\"(max-width: 947px) 100vw, 947px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 947px; --smush-placeholder-aspect-ratio: 947\/722;\" \/><figcaption class=\"wp-element-caption\"><strong>Joan Comella<\/strong>, director del Instituto de Investigaciones Sant Joan de D\u00e9u (SJD).<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"947\" height=\"723\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Manuel-Salmeron.jpg\" alt=\"\" class=\"wp-image-132433 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Manuel-Salmeron.jpg 947w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Manuel-Salmeron-300x229.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Manuel-Salmeron-768x586.jpg 768w\" data-sizes=\"(max-width: 947px) 100vw, 947px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 947px; --smush-placeholder-aspect-ratio: 947\/723;\" \/><figcaption class=\"wp-element-caption\"><strong>Manuel Salmer\u00f3n<\/strong>, director del Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC).<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>La jornada se ha inaugurado por <strong>Joan Comella<\/strong>, director del Instituto de Investigaciones Sant Joan de D\u00e9u (SJD), y por <strong>Manuel Salmer\u00f3n<\/strong>, director del Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC). Ambos han destacado la colaboraci\u00f3n estrat\u00e9gica entre las dos instituciones, cuyo objetivo no es simplemente sumar proyectos, sino construir un \u00fanico proyecto conjunto. En ese sentido, la jornada Nano Rare Diseases Day 2026 tambi\u00e9n ha servido para marcar el inicio visible de esa alianza, que sit\u00faa a los pacientes y a sus familias en el centro de las prioridades. Adem\u00e1s, ambos directores coincidieron en que la uni\u00f3n entre nanomedicina y bioingenier\u00eda abre oportunidades para compartir espacios, conocimiento y proyectos entre el IBEC y Sant Joan de D\u00e9u.<\/p>\n\n\n\n<p>En su intervenci\u00f3n Comella ha subrayado la importancia de desarrollar nuevos enfoques de investigaci\u00f3n que integren diferentes niveles del conocimiento biom\u00e9dico: \u201cNecesitamos modelos funcionales de bioingenier\u00eda que conecten los distintos aspectos de la enfermedad y, sobre todo, que est\u00e9n vinculados con los pacientes y sus familias. En este contexto, la colaboraci\u00f3n entre el IBEC y Sant Joan de D\u00e9u puede generar avances reales y contribuir a mejorar la calidad de vida de los pacientes.\u201d A su vez, Salmer\u00f3n ha destacado el potencial de la colaboraci\u00f3n entre ambas instituciones para impulsar nuevas estrategias terap\u00e9uticas: \u201cEsta colaboraci\u00f3n es especialmente estimulante porque nos permitir\u00e1 avanzar hacia el tratamiento y la cura de enfermedades raras mediante la combinaci\u00f3n de nanomedicina y bioingenier\u00eda.\u201d<\/p>\n\n\n\n<p>A continuaci\u00f3n, han tenido lugar las presentaciones cient\u00edficas, enfocadas en los \u00faltimos avances cient\u00edficos en el \u00e1mbito de diferentes enfermedades raras.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Samitier_20260305_102008-1024x768.jpg\" alt=\"\" class=\"wp-image-132437 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Samitier_20260305_102008-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Samitier_20260305_102008-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Samitier_20260305_102008-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Samitier_20260305_102008-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Samitier_20260305_102008-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Josep Samitier<\/strong>, coordinador cient\u00edfico de Nanomed Spain.<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elena-Garreta_20260305_103233-1024x768.jpg\" alt=\"\" class=\"wp-image-132440 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elena-Garreta_20260305_103233-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elena-Garreta_20260305_103233-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elena-Garreta_20260305_103233-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elena-Garreta_20260305_103233-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elena-Garreta_20260305_103233-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Elena Garreta<\/strong>, investigadora senior del IBEC y coordinadora de la Plataforma de Biobancos y Biomodelos del ISCIII.<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Josep Samitier<\/strong>, coordinador cient\u00edfico de Nanomed Spain, ha hecho un repaso de la historia de la nanomedicina y de los \u00faltimos avances que han permitido mejorar el diagn\u00f3stico y tratamiento de algunas enfermedades, destacando su gran desarrollo cient\u00edfico en los \u00faltimos 30 a\u00f1os. Concretamente, Samitier ha destacado el papel fundamental de la nanomedicina durante la pandemia de COVID-19 con las vacunas de ARN, primera vez en la historia que se usaba de manera masiva demostrando su seguridad y fiabilidad. Adem\u00e1s, tambi\u00e9n ha mencionado el papel de Nanomed Spain como una valiosa herramienta a nivel espa\u00f1ol. Con m\u00e1s de 190 instituciones, Nanomed Spain tiene el objetivo de fomentar el dialogo y las sinergias entre centros de investigaci\u00f3n, hospitales, empresas y pacientes, pasando por los \u00f3rganos de gobierno, para llevar los avances en nanomedicina a la sociedad.<\/p>\n\n\n\n<p><strong>Elena Garreta<\/strong>, investigadora senior del IBEC y coordinadora de la Plataforma de Biobancos y Biomodelos del ISCIII, ha presentado las c\u00e9lulas pluripotentes y los organoides como herramientas para entender c\u00f3mo se desarrollan las enfermedades y para impulsar metodolog\u00edas para producir biomodelos que simulen el \u00f3rgano de origen. Adem\u00e1s, tambi\u00e9n ha mencionado su gran potencial para el cribado de f\u00e1rmacos y en un futuro, para la regeneraci\u00f3n de \u00f3rganos.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Georgia-Sarquella_20260305_110034-1024x768.jpg\" alt=\"\" class=\"wp-image-132443 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Georgia-Sarquella_20260305_110034-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Georgia-Sarquella_20260305_110034-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Georgia-Sarquella_20260305_110034-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Georgia-Sarquella_20260305_110034-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Georgia-Sarquella_20260305_110034-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Georgia Sarquella<\/strong> (SJD).<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Anna-Lagunas-y-Marina-Gianotti_20260305_112322-1024x768.jpg\" alt=\"\" class=\"wp-image-132446 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Anna-Lagunas-y-Marina-Gianotti_20260305_112322-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Anna-Lagunas-y-Marina-Gianotti_20260305_112322-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Anna-Lagunas-y-Marina-Gianotti_20260305_112322-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Anna-Lagunas-y-Marina-Gianotti_20260305_112322-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Anna-Lagunas-y-Marina-Gianotti_20260305_112322-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Anna Lagunas y Marina In\u00e9s Gianotti<\/strong> (IBEC).<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Georgia Sarquella<\/strong>, de SJD, ha explicado los resultados extraordinarios en el desarrollo de marcapasos adaptados a beb\u00e9s y ni\u00f1os, mencionando las dificultades a las que se enfrentan a diario para conseguir llevar a la poblaci\u00f3n infantil las soluciones que necesitan, adaptadas a su edad y fisiolog\u00eda. &nbsp;<\/p>\n\n\n\n<p><strong>Anna Lagunas y Marina In\u00e9s Gianotti<\/strong>, del IBEC han destacado nuevas estrategias y modelos fisiol\u00f3gicos para evaluar terapias de edici\u00f3n gen\u00e9tica en distrofias musculares por d\u00e9ficit de col\u00e1geno VI.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Lara-Cantarero_20260305_120555-1024x768.jpg\" alt=\"\" class=\"wp-image-132449 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Lara-Cantarero_20260305_120555-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Lara-Cantarero_20260305_120555-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Lara-Cantarero_20260305_120555-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Lara-Cantarero_20260305_120555-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Lara-Cantarero_20260305_120555-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Lara Cantero<\/strong> (SJD).<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elisabet-Gonzalez_20260305_122123-1024x768.jpg\" alt=\"\" class=\"wp-image-132452 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elisabet-Gonzalez_20260305_122123-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elisabet-Gonzalez_20260305_122123-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elisabet-Gonzalez_20260305_122123-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elisabet-Gonzalez_20260305_122123-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Elisabet-Gonzalez_20260305_122123-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Elisabet Gonzalez <\/strong>(ICMAB-CSIC y Delbios Pharmaceuticals).<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Lara Cantero<\/strong>, de SJD ha centrado su presentaci\u00f3n en la enfermedad de Charcot-Marie Tooth, un&nbsp;grupo de trastornos neurol\u00f3gicos hereditarios y muy agresivos que da\u00f1an los nervios perif\u00e9ricos, provocando debilidad muscular, atrofia y p\u00e9rdida de sensibilidad. Su estudio se centra en conocer mejor los sitios de contacto entre membranas asociados a esa enfermedad para poder identificar posibles dianas terap\u00e9uticas.<\/p>\n\n\n\n<p><strong>Elisabet Gonzalez <\/strong>del ICMAB-CSIC y Delbios Pharmaceuticals ha presentado los avances de una nueva terapia enzim\u00e1tica liposomal para la enfermedad de Fabry. Concretamente ha descrito \u201cnanoGLA\u201d, un liposoma funcionalizado que contiene una prote\u00edna humana recombinante. Este nuevo enfoque de nanotecnolog\u00eda se muestra como alternativa al tratamiento actual, inespec\u00edfico y poco eficiente, y permite aumentar la vida \u00fatil de la enzima y dirigirla a las dianas de inter\u00e9s dentro del cuerpo.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Rafa-Artuch_20260305_124548-1024x768.jpg\" alt=\"\" class=\"wp-image-132455 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Rafa-Artuch_20260305_124548-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Rafa-Artuch_20260305_124548-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Rafa-Artuch_20260305_124548-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Rafa-Artuch_20260305_124548-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Rafa-Artuch_20260305_124548-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Rafael Artuch<\/strong> (SJD).<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"768\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Ester-Costafreda_20260305_125835-1024x768.jpg\" alt=\"\" class=\"wp-image-132458 lazyload\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Ester-Costafreda_20260305_125835-1024x768.jpg 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Ester-Costafreda_20260305_125835-300x225.jpg 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Ester-Costafreda_20260305_125835-768x576.jpg 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Ester-Costafreda_20260305_125835-1536x1152.jpg 1536w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Ester-Costafreda_20260305_125835-2048x1536.jpg 2048w\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1024px; --smush-placeholder-aspect-ratio: 1024\/768;\" \/><figcaption class=\"wp-element-caption\"><strong>Ester Costafreda<\/strong> (Asociaci\u00f3n SAMS: S\u00edndromes Arr\u00edtmicos relacionados con la muerte s\u00fabita).<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Rafael Artuch<\/strong> de SJD ha explicado c\u00f3mo el fenotipado del metabolismo dirigido a modelos animales y celulares puede ayudar a entender mejor algunas enfermedades y a encontrar posibles dianas para buscar tratamientos.<\/p>\n\n\n\n<p>La jornada ha concluido con la ponencia de <strong>Ester Costafreda<\/strong>, de la Asociaci\u00f3n SAMS (S\u00edndromes Arr\u00edtmicos relacionados con la muerte s\u00fabita). Su presentaci\u00f3n ha puesto de manifiesto el punto de vista de los pacientes y sus familias, y la importancia de trabajar en conjunto. Costafreda ha hecho especial hincapi\u00e9 en la importancia de integrar la experiencia de los pacientes con la ciencia y de conocer sus inquietudes y expectativas para ayudar a orientar mejor la investigaci\u00f3n y encontrar soluciones adaptadas a las necesidades reales, y en menor tiempo.<\/p>\n\n\n\n<p>La celebraci\u00f3n de jornadas como el Nano Rare Diseases Day contribuye a visibilizar las enfermedades raras y a impulsar la investigaci\u00f3n orientada al desarrollo de nuevas estrategias para el diagn\u00f3stico y terapias. En este contexto, la nanomedicina se perfila como una herramienta con un notable potencial para abordar algunos de los retos asociados a esas enfermedades. Colaboraciones como la de Instituto de Investigaci\u00f3n Sant Joan de D\u00e9u y el IBEC reflejan la importancia de fortalecer las sinergias entre investigaci\u00f3n b\u00e1sica y pr\u00e1ctica cl\u00ednica para conseguir desde una mejora de los diagn\u00f3sticos hasta el dise\u00f1o de tratamientos m\u00e1s espec\u00edficos. Solamente a trav\u00e9s de alianzas como esta, y con la mirada puesta en el sector industrial y las asociaciones de pacientes, seremos capaces de trasladar los resultados al \u00e1mbito asistencial y a la sociedad.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Expertos en nanomedicina se han reunido hoy, 05 de marzo, para debatir los \u00faltimos avances en el estudio, diagn\u00f3stico y tratamiento de las enfermedades raras. La jornada Nano Rare Diseases &#8230; <a title=\"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day\" class=\"read-more\" href=\"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/\" aria-label=\"More on Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day\">Read more<\/a><\/p>\n","protected":false},"author":24,"featured_media":132427,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[94],"tags":[1948,1951],"post_formats":[],"class_list":["post-132465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-institucionales","tag-nano-rare-diseases-day-es","tag-nanomed-spain-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day - Institute for Bioengineering of Catalonia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day - Institute for Bioengineering of Catalonia\" \/>\n<meta property=\"og:description\" content=\"Expertos en nanomedicina se han reunido hoy, 05 de marzo, para debatir los \u00faltimos avances en el estudio, diagn\u00f3stico y tratamiento de las enfermedades raras. La jornada Nano Rare Diseases ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/\" \/>\n<meta property=\"og:site_name\" content=\"Institute for Bioengineering of Catalonia\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-05T12:17:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-09T12:39:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1611\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bia Moreno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bia Moreno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/\"},\"author\":{\"name\":\"Bia Moreno\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/person\\\/b553413d524d76a399e659509449f8ec\"},\"headline\":\"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day\",\"datePublished\":\"2026-03-05T12:17:16+00:00\",\"dateModified\":\"2026-03-09T12:39:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/\"},\"wordCount\":1358,\"publisher\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Para-portada_OK-scaled.jpg\",\"keywords\":[\"Nano Rare diseases day\",\"NANOMED Spain\"],\"articleSection\":[\"Noticias institucionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/\",\"name\":\"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day - Institute for Bioengineering of Catalonia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Para-portada_OK-scaled.jpg\",\"datePublished\":\"2026-03-05T12:17:16+00:00\",\"dateModified\":\"2026-03-09T12:39:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Para-portada_OK-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/Para-portada_OK-scaled.jpg\",\"width\":2560,\"height\":1611},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#website\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/\",\"name\":\"Institute for Bioengineering of Catalonia\",\"description\":\"Bioengineering solutions for health\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibecbarcelona.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\",\"name\":\"Institute for Bioengineering of Catalonia\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-IBEC_20ANYS_GRIS.png\",\"contentUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-IBEC_20ANYS_GRIS.png\",\"width\":696,\"height\":257,\"caption\":\"Institute for Bioengineering of Catalonia\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/person\\\/b553413d524d76a399e659509449f8ec\",\"name\":\"Bia Moreno\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g\",\"caption\":\"Bia Moreno\"},\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/author\\\/bmoreno\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day - Institute for Bioengineering of Catalonia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/","og_locale":"es_ES","og_type":"article","og_title":"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day - Institute for Bioengineering of Catalonia","og_description":"Expertos en nanomedicina se han reunido hoy, 05 de marzo, para debatir los \u00faltimos avances en el estudio, diagn\u00f3stico y tratamiento de las enfermedades raras. La jornada Nano Rare Diseases ... Read more","og_url":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/","og_site_name":"Institute for Bioengineering of Catalonia","article_published_time":"2026-03-05T12:17:16+00:00","article_modified_time":"2026-03-09T12:39:55+00:00","og_image":[{"width":2560,"height":1611,"url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg","type":"image\/jpeg"}],"author":"Bia Moreno","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Bia Moreno","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#article","isPartOf":{"@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/"},"author":{"name":"Bia Moreno","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/person\/b553413d524d76a399e659509449f8ec"},"headline":"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day","datePublished":"2026-03-05T12:17:16+00:00","dateModified":"2026-03-09T12:39:55+00:00","mainEntityOfPage":{"@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/"},"wordCount":1358,"publisher":{"@id":"https:\/\/ibecbarcelona.eu\/#organization"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#primaryimage"},"thumbnailUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg","keywords":["Nano Rare diseases day","NANOMED Spain"],"articleSection":["Noticias institucionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/","url":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/","name":"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day - Institute for Bioengineering of Catalonia","isPartOf":{"@id":"https:\/\/ibecbarcelona.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#primaryimage"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#primaryimage"},"thumbnailUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg","datePublished":"2026-03-05T12:17:16+00:00","dateModified":"2026-03-09T12:39:55+00:00","breadcrumb":{"@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#primaryimage","url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg","contentUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg","width":2560,"height":1611},{"@type":"BreadcrumbList","@id":"https:\/\/ibecbarcelona.eu\/es\/nanomedicina-para-enfermedades-raras-expertos-analizan-nuevos-enfoques-en-el-nano-rare-diseases-day\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibecbarcelona.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Nanomedicina para enfermedades raras: expertos analizan nuevos enfoques en el Nano Rare Diseases Day"}]},{"@type":"WebSite","@id":"https:\/\/ibecbarcelona.eu\/#website","url":"https:\/\/ibecbarcelona.eu\/","name":"Institute for Bioengineering of Catalonia","description":"Bioengineering solutions for health","publisher":{"@id":"https:\/\/ibecbarcelona.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibecbarcelona.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ibecbarcelona.eu\/#organization","name":"Institute for Bioengineering of Catalonia","url":"https:\/\/ibecbarcelona.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/logo\/image\/","url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/01\/cropped-IBEC_20ANYS_GRIS.png","contentUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/01\/cropped-IBEC_20ANYS_GRIS.png","width":696,"height":257,"caption":"Institute for Bioengineering of Catalonia"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/person\/b553413d524d76a399e659509449f8ec","name":"Bia Moreno","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb483bca1d652e4f51c1831a5fbd1448c61e5d11f6b6f74fc8efed0509d20438?s=96&d=mm&r=g","caption":"Bia Moreno"},"url":"https:\/\/ibecbarcelona.eu\/es\/author\/bmoreno\/"}]}},"AFP_featured_media_urls":{"full":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-scaled.jpg",2560,1611,false],"thumbnail":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-150x150.jpg",150,150,true],"medium":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-300x189.jpg",300,189,true],"medium_large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-768x483.jpg",768,483,true],"large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada_OK-1024x644.jpg",1024,644,true]},"AFP_attachments":{"full":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada-scaled.jpg",2560,1920,false],"thumbnail":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada-150x150.jpg",150,150,true],"medium":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada-300x225.jpg",300,225,true],"medium_large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada-768x576.jpg",768,576,true],"large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/03\/Para-portada-1024x768.jpg",1024,768,true]},"AFP_videos":[],"AFP_video_blocks":"","AFP_category_names":["Noticias institucionales"],"_links":{"self":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts\/132465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/comments?post=132465"}],"version-history":[{"count":1,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts\/132465\/revisions"}],"predecessor-version":[{"id":132466,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/posts\/132465\/revisions\/132466"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/media\/132427"}],"wp:attachment":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/media?parent=132465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/categories?post=132465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tags?post=132465"},{"taxonomy":"post_format","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/post_formats?post=132465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}