{"id":87661,"date":"2021-10-07T14:03:50","date_gmt":"2021-10-07T12:03:50","guid":{"rendered":"https:\/\/ibecbarcelona.eu\/?post_type=tribe_events&#038;p=87661&#038;lang=es"},"modified":"2021-11-08T17:09:08","modified_gmt":"2021-11-08T16:09:08","slug":"adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia","status":"publish","type":"tribe_events","link":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/","title":{"rendered":"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! &#8211; Semana de la ciencia"},"content":{"rendered":"<h1>\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica!<\/h1>\n<p><a href=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM.png\"><img decoding=\"async\" class=\"aligncenter wp-image-87711 lazyload\" data-src=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png\" alt=\"\" width=\"450\" height=\"324\" data-srcset=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png 1024w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-300x216.png 300w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-768x553.png 768w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-150x108.png 150w, https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM.png 1376w\" data-sizes=\"(max-width: 450px) 100vw, 450px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 450px; --smush-placeholder-aspect-ratio: 450\/324;\" \/><\/a><\/p>\n<p>Desde que en la d\u00e9cada de los 80 se inventara el microscopio de sonda de\u00a0barrido,\u00a0han sido muchos y\u00a0muy relevantes\u00a0los descubrimientos que estas t\u00e9cnicas han proporcionado al conocimiento cient\u00edfico. Aun hoy, es un instrumento capaz de detectar fen\u00f3menos incre\u00edbles que se dan en la escala de lo muy peque\u00f1o, fen\u00f3menos que nos acercan m\u00e1s y m\u00e1s a la comprensi\u00f3n de este mundo sujeto a fuerzas muy distintas de lo cotidiano.<\/p>\n<p>En\u00a0esta\u00a0charla\u00a0con el investigador Rub\u00e9n Mill\u00e1n del Instituto de Bioingenier\u00eda de Catalu\u00f1a (IBEC), podr\u00e9is descubrir c\u00f3mo funciona un microscopio de AFM, tendr\u00e9is\u00a0la posibilidad de probar en vivo el juego \u201cCatch me AFM\u201d, y de conocer a nuestra superhero\u00edna cient\u00edfica IBBI.<\/p>\n<p>\u00a1No os lo pod\u00e9is perder! Inscripciones <a href=\"https:\/\/events.ibecbarcelona.eu\/setmana-de-la-ciencia\/\" target=\"_blank\" rel=\"noopener\">aqu\u00ed<\/a>.<\/p>\n<hr \/>\n<p>Charla divulgativa sobre la microscopia AFM en el marco de la \u00ab<a href=\"https:\/\/setmanaciencia.fundaciorecerca.cat\/frontend\/\" target=\"_blank\" rel=\"noopener\">Setmana de la ci\u00e8ncia 2021<\/a>\u00ab<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! Desde que en la d\u00e9cada de los 80 se inventara el microscopio de sonda de\u00a0barrido,\u00a0han sido muchos &#8230; <a title=\"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! &#8211; Semana de la ciencia\" class=\"read-more\" href=\"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/\" aria-label=\"More on \u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! &#8211; Semana de la ciencia\">Read more<\/a><\/p>\n","protected":false},"author":4,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[371],"class_list":["post-87661","tribe_events","type-tribe_events","status-publish","hentry","tribe_events_cat-outreach-es","cat_outreach-es"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! - Semana de la ciencia - Institute for Bioengineering of Catalonia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! - Semana de la ciencia - Institute for Bioengineering of Catalonia\" \/>\n<meta property=\"og:description\" content=\"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! Desde que en la d\u00e9cada de los 80 se inventara el microscopio de sonda de\u00a0barrido,\u00a0han sido muchos ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Institute for Bioengineering of Catalonia\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-08T16:09:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/\",\"name\":\"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! - Semana de la ciencia - Institute for Bioengineering of Catalonia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AFM-1024x737.png\",\"datePublished\":\"2021-10-07T12:03:50+00:00\",\"dateModified\":\"2021-11-08T16:09:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AFM-1024x737.png\",\"contentUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2021\\\/10\\\/AFM-1024x737.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/event\\\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ibecbarcelona.eu\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Esdeveniments\",\"item\":\"https:\\\/\\\/ibecbarcelona.eu\\\/ca\\\/calendar\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! &#8211; Semana de la ciencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#website\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/\",\"name\":\"Institute for Bioengineering of Catalonia\",\"description\":\"Bioengineering solutions for health\",\"publisher\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ibecbarcelona.eu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#organization\",\"name\":\"Institute for Bioengineering of Catalonia\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-IBEC_20ANYS_GRIS.png\",\"contentUrl\":\"https:\\\/\\\/ibecbarcelona.eu\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/cropped-IBEC_20ANYS_GRIS.png\",\"width\":696,\"height\":257,\"caption\":\"Institute for Bioengineering of Catalonia\"},\"image\":{\"@id\":\"https:\\\/\\\/ibecbarcelona.eu\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! - Semana de la ciencia - Institute for Bioengineering of Catalonia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/","og_locale":"es_ES","og_type":"article","og_title":"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! - Semana de la ciencia - Institute for Bioengineering of Catalonia","og_description":"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! Desde que en la d\u00e9cada de los 80 se inventara el microscopio de sonda de\u00a0barrido,\u00a0han sido muchos ... Read more","og_url":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/","og_site_name":"Institute for Bioengineering of Catalonia","article_modified_time":"2021-11-08T16:09:08+00:00","og_image":[{"url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/","url":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/","name":"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! - Semana de la ciencia - Institute for Bioengineering of Catalonia","isPartOf":{"@id":"https:\/\/ibecbarcelona.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/#primaryimage"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/#primaryimage"},"thumbnailUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png","datePublished":"2021-10-07T12:03:50+00:00","dateModified":"2021-11-08T16:09:08+00:00","breadcrumb":{"@id":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/#primaryimage","url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png","contentUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png"},{"@type":"BreadcrumbList","@id":"https:\/\/ibecbarcelona.eu\/es\/event\/adentrate-en-la-nano-escala-descubre-y-juega-con-el-microscopio-de-fuerza-atomica-semana-de-la-ciencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ibecbarcelona.eu\/es\/"},{"@type":"ListItem","position":2,"name":"Esdeveniments","item":"https:\/\/ibecbarcelona.eu\/ca\/calendar\/"},{"@type":"ListItem","position":3,"name":"\u00a1Ad\u00e9ntrate en la nano-escala: descubre y juega con el Microscopio de Fuerza At\u00f3mica! &#8211; Semana de la ciencia"}]},{"@type":"WebSite","@id":"https:\/\/ibecbarcelona.eu\/#website","url":"https:\/\/ibecbarcelona.eu\/","name":"Institute for Bioengineering of Catalonia","description":"Bioengineering solutions for health","publisher":{"@id":"https:\/\/ibecbarcelona.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ibecbarcelona.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ibecbarcelona.eu\/#organization","name":"Institute for Bioengineering of Catalonia","url":"https:\/\/ibecbarcelona.eu\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/logo\/image\/","url":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/01\/cropped-IBEC_20ANYS_GRIS.png","contentUrl":"https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2026\/01\/cropped-IBEC_20ANYS_GRIS.png","width":696,"height":257,"caption":"Institute for Bioengineering of Catalonia"},"image":{"@id":"https:\/\/ibecbarcelona.eu\/#\/schema\/logo\/image\/"}}]}},"AFP_featured_media_urls":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false},"AFP_attachments":{"full":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM.png",1376,991,false],"thumbnail":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-150x150.png",150,150,true],"medium":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-300x216.png",300,216,true],"medium_large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-768x553.png",768,553,true],"large":["https:\/\/ibecbarcelona.eu\/wp-content\/uploads\/2021\/10\/AFM-1024x737.png",1024,737,true]},"AFP_videos":[],"AFP_video_blocks":"","AFP_category_names":[],"_links":{"self":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tribe_events\/87661","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":5,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tribe_events\/87661\/revisions"}],"predecessor-version":[{"id":88413,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tribe_events\/87661\/revisions\/88413"}],"wp:attachment":[{"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/media?parent=87661"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tags?post=87661"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/ibecbarcelona.eu\/es\/wp-json\/wp\/v2\/tribe_events_cat?post=87661"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}